{"id":9938,"date":"2024-09-12T23:35:05","date_gmt":"2024-09-12T16:35:05","guid":{"rendered":"https:\/\/ccl-laos.org\/?post_type=events&#038;p=9938"},"modified":"2024-10-07T15:20:05","modified_gmt":"2024-10-07T08:20:05","slug":"conference_dauplay","status":"publish","type":"events","link":"https:\/\/ccl-laos.org\/lo\/events\/conference_dauplay\/","title":{"rendered":"Le Laos dans les ann\u00e9es 20 &#8211; le fonds photographique de Jean-Jacques DAUPLAY"},"template":"","linked_activities":[57],"event_type":[65],"class_list":["post-9938","events","type-events","status-publish","hentry","linked_activities-culture","event_type-culture"],"acf":[],"_links":{"self":[{"href":"https:\/\/ccl-laos.org\/lo\/wp-json\/wp\/v2\/events\/9938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccl-laos.org\/lo\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/ccl-laos.org\/lo\/wp-json\/wp\/v2\/types\/events"}],"wp:attachment":[{"href":"https:\/\/ccl-laos.org\/lo\/wp-json\/wp\/v2\/media?parent=9938"}],"wp:term":[{"taxonomy":"linked_activities","embeddable":true,"href":"https:\/\/ccl-laos.org\/lo\/wp-json\/wp\/v2\/linked_activities?post=9938"},{"taxonomy":"event_type","embeddable":true,"href":"https:\/\/ccl-laos.org\/lo\/wp-json\/wp\/v2\/event_type?post=9938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}